{"id":1282,"date":"2022-02-04T10:32:29","date_gmt":"2022-02-04T10:32:29","guid":{"rendered":"https:\/\/alfilm.berlin\/presse\/"},"modified":"2026-04-08T18:16:04","modified_gmt":"2026-04-08T18:16:04","slug":"presse","status":"publish","type":"page","link":"https:\/\/alfilm.berlin\/ar\/presse\/","title":{"rendered":"\u0627\u0644\u0635\u062d\u0627\u0641\u0629"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\r\n<h1 class=\"wp-block-heading\" id=\"presse\">\u0627\u0644\u0635\u062d\u0627\u0641\u0629<\/h1>\r\n<p>\u00a0<\/p>\r\n\r\n<div class=\"wp-block-columns has-2-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<h2 class=\"wp-block-heading\" id=\"pressestelle\">\u0627\u0644\u0645\u0643\u062a\u0628 \u0627\u0644\u0635\u062d\u0641\u064a<\/h2>\r\n<p style=\"text-align: right;\">\u064a\u0631\u062c\u0649 \u0625\u0631\u0633\u0627\u0644 \u0627\u0644\u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0627\u062a \u0627\u0644\u0635\u062d\u0641\u064a\u0629 (\u0644\u0644\u0635\u062d\u0627\u0641\u0629 \u0627\u0644\u0639\u0631\u0628\u064a\u0629) \u0625\u0644\u0649<br \/>\u0646\u0632\u064a\u0647\u0629 \u0633\u0639\u064a\u062f<br \/>nazeeha@alfilm.berlin<\/p>\r\n<p>\u064a\u0631\u062c\u0649 \u0625\u0631\u0633\u0627\u0644 \u0627\u0644\u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0627\u062a \u0627\u0644\u0635\u062d\u0641\u064a\u0629 \u0644\u0644\u0635\u062d\u0627\u0641\u0629 \u0627\u0644\u0625\u0646\u062c\u0644\u064a\u0632\u064a\u0629 \u0648\u0627\u0644\u0623\u0644\u0645\u0627\u0646\u064a\u0629 \u0625\u0644\u0649<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"fabrikpublik\"><strong>fabrikpublik<\/strong><\/h3>\r\n\r\n<p>Kreatives PR- &amp; Projektmanagement<br \/>www.fabrikpublik.de<br \/><a class=\"\" href=\"mailto:presse@fabrikpublik.de\">presse@fabrikpublik.de<\/a><\/p>\r\n\r\n<p><strong>Christiane Dram\u00e9 <\/strong><br \/>+49 173 8741939<br \/><a href=\"mailto:christiane.drame@fabrikpublik.de\">christiane.drame@fabrikpublik.de<\/a><\/p>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<h2 class=\"wp-block-heading\" id=\"presse-verteiler\" style=\"text-align: center;\">\u0642\u0627\u0626\u0645\u0629 \u0628\u0631\u064a\u062f \u0627\u0644\u0635\u062d\u0627\u0641\u0629<\/h2>\r\n\r\n\r\n  \n  \n  <div class=\"\n    mailpoet_form_popup_overlay\n      \"><\/div>\n  <div\n    id=\"mailpoet_form_2\"\n    class=\"\n      mailpoet_form\n      mailpoet_form_html\n      mailpoet_form_position_\n      mailpoet_form_animation_\n    \"\n      >\n\n    <style type=\"text\/css\">\n     #mailpoet_form_2 .mailpoet_form {  }\n#mailpoet_form_2 .mailpoet_column_with_background { padding: 10px; }\n#mailpoet_form_2 .mailpoet_form_column:not(:first-child) { margin-left: 20px; }\n#mailpoet_form_2 .mailpoet_paragraph { line-height: 20px; margin-bottom: 20px; }\n#mailpoet_form_2 .mailpoet_segment_label, #mailpoet_form_2 .mailpoet_text_label, #mailpoet_form_2 .mailpoet_textarea_label, #mailpoet_form_2 .mailpoet_select_label, #mailpoet_form_2 .mailpoet_radio_label, #mailpoet_form_2 .mailpoet_checkbox_label, #mailpoet_form_2 .mailpoet_list_label, #mailpoet_form_2 .mailpoet_date_label { display: block; font-weight: normal; }\n#mailpoet_form_2 .mailpoet_text, #mailpoet_form_2 .mailpoet_textarea, #mailpoet_form_2 .mailpoet_select, #mailpoet_form_2 .mailpoet_date_month, #mailpoet_form_2 .mailpoet_date_day, #mailpoet_form_2 .mailpoet_date_year, #mailpoet_form_2 .mailpoet_date { display: block; }\n#mailpoet_form_2 .mailpoet_text, #mailpoet_form_2 .mailpoet_textarea { width: 200px; }\n#mailpoet_form_2 .mailpoet_checkbox {  }\n#mailpoet_form_2 .mailpoet_submit {  }\n#mailpoet_form_2 .mailpoet_divider {  }\n#mailpoet_form_2 .mailpoet_message {  }\n#mailpoet_form_2 .mailpoet_form_loading { width: 30px; text-align: center; line-height: normal; }\n#mailpoet_form_2 .mailpoet_form_loading > span { width: 5px; height: 5px; background-color: #5b5b5b; }#mailpoet_form_2{border: 0px solid #abb8c3;border-radius: 0px;color: #000000;text-align: left;}#mailpoet_form_2 form.mailpoet_form {padding: 20px;}#mailpoet_form_2{width: 100%;}#mailpoet_form_2 .mailpoet_message {margin: 0; padding: 0 20px;}#mailpoet_form_2 .mailpoet_paragraph.last {margin-bottom: 0} @media (max-width: 500px) {#mailpoet_form_2 {background-image: none;}} @media (min-width: 500px) {#mailpoet_form_2 .last .mailpoet_paragraph:last-child {margin-bottom: 0}}  @media (max-width: 500px) {#mailpoet_form_2 .mailpoet_form_column:last-child .mailpoet_paragraph:last-child {margin-bottom: 0}} \n    <\/style>\n\n    <form\n      target=\"_self\"\n      method=\"post\"\n      action=\"https:\/\/alfilm.berlin\/wp-admin\/admin-post.php?action=mailpoet_subscription_form\"\n      class=\"mailpoet_form mailpoet_form_form mailpoet_form_html\"\n      novalidate\n      data-delay=\"\"\n      data-exit-intent-enabled=\"\"\n      data-font-family=\"\"\n      data-cookie-expiration-time=\"\"\n    >\n      <input type=\"hidden\" name=\"data[form_id]\" value=\"2\" \/>\n      <input type=\"hidden\" name=\"token\" value=\"66d4bb9c13\" \/>\n      <input type=\"hidden\" name=\"api_version\" value=\"v1\" \/>\n      <input type=\"hidden\" name=\"endpoint\" value=\"subscribers\" \/>\n      <input type=\"hidden\" name=\"mailpoet_method\" value=\"subscribe\" \/>\n\n      <label class=\"mailpoet_hp_email_label\" style=\"display: none !important;\">\u064a\u0631\u062c\u0649 \u062a\u0631\u0643 \u0647\u0630\u0627 \u0627\u0644\u062d\u0642\u0644 \u0641\u0627\u0631\u063a\u0627<input type=\"email\" name=\"data[email]\"\/><\/label><h3 class=\"mailpoet-heading \" style=\"text-align: left\"><\/h3>\n<div class=\"mailpoet_paragraph \"><input type=\"text\" autocomplete=\"given-name\" class=\"mailpoet_text\" id=\"form_first_name_2\" name=\"data[form_field_M2FkYjhhNmIxYWJmX2ZpcnN0X25hbWU=]\" title=\"Vorname\" value=\"\" style=\"width:100%;box-sizing:border-box;padding:5px;margin: 0 auto 0 0;\" data-automation-id=\"form_first_name\"  placeholder=\"Vorname\" aria-label=\"Vorname\" data-parsley-errors-container=\".mailpoet_error_19y31\" data-parsley-names='[&quot;\u0627\u0644\u0631\u062c\u0627\u0621 \u062a\u062d\u062f\u064a\u062f \u0627\u0633\u0645 \u0635\u0627\u0644\u062d&quot;,&quot;\u0627\u0644\u0639\u0646\u0627\u0648\u064a\u0646 \u0627\u0644\u0645\u0648\u062c\u0648\u062f\u0629 \u0641\u064a \u0627\u0644\u0623\u0633\u0645\u0627\u0621 \u063a\u064a\u0631 \u0645\u0633\u0645\u0648\u062d \u0628\u0647\u0627\u060c \u064a\u0631\u062c\u0649 \u0625\u0636\u0627\u0641\u0629 \u0627\u0633\u0645\u0643 \u0628\u062f\u0644\u0627\u064b \u0645\u0646 \u0630\u0644\u0643.&quot;]'\/><span class=\"mailpoet_error_19y31\"><\/span><\/div>\n<div class=\"mailpoet_paragraph \"><input type=\"text\" autocomplete=\"family-name\" class=\"mailpoet_text\" id=\"form_last_name_2\" name=\"data[form_field_MDNjNzE2ZTY2ZGRkX2xhc3RfbmFtZQ==]\" title=\"Nachname\" value=\"\" style=\"width:100%;box-sizing:border-box;padding:5px;margin: 0 auto 0 0;\" data-automation-id=\"form_last_name\"  placeholder=\"Nachname\" aria-label=\"Nachname\" data-parsley-errors-container=\".mailpoet_error_9apy6\" data-parsley-names='[&quot;\u0627\u0644\u0631\u062c\u0627\u0621 \u062a\u062d\u062f\u064a\u062f \u0627\u0633\u0645 \u0635\u0627\u0644\u062d&quot;,&quot;\u0627\u0644\u0639\u0646\u0627\u0648\u064a\u0646 \u0627\u0644\u0645\u0648\u062c\u0648\u062f\u0629 \u0641\u064a \u0627\u0644\u0623\u0633\u0645\u0627\u0621 \u063a\u064a\u0631 \u0645\u0633\u0645\u0648\u062d \u0628\u0647\u0627\u060c \u064a\u0631\u062c\u0649 \u0625\u0636\u0627\u0641\u0629 \u0627\u0633\u0645\u0643 \u0628\u062f\u0644\u0627\u064b \u0645\u0646 \u0630\u0644\u0643.&quot;]'\/><span class=\"mailpoet_error_9apy6\"><\/span><\/div>\n<div class=\"mailpoet_paragraph \"><input type=\"email\" autocomplete=\"email\" class=\"mailpoet_text\" id=\"form_email_2\" name=\"data[form_field_Y2MzYzhhYjY4MGRkX2VtYWls]\" title=\"E-Mail-Adresse\" value=\"\" style=\"width:100%;box-sizing:border-box;padding:5px;margin: 0 auto 0 0;\" data-automation-id=\"form_email\"  placeholder=\"E-Mail-Adresse *\" aria-label=\"E-Mail-Adresse *\" data-parsley-errors-container=\".mailpoet_error_r2gqr\" data-parsley-required=\"true\" required aria-required=\"true\" data-parsley-minlength=\"6\" data-parsley-maxlength=\"150\" data-parsley-type-message=\"\u064a\u062c\u0628 \u0623\u0646 \u062a\u0643\u0648\u0646 \u0647\u0630\u0647 \u0627\u0644\u0642\u064a\u0645\u0629 \u0628\u0631\u064a\u062f\u064b\u0627 \u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u064b\u0627 \u0635\u0627\u0644\u062d\u064b\u0627.\" data-parsley-required-message=\"\u0647\u0630\u0627 \u0627\u0644\u062d\u0642\u0644 \u0645\u0637\u0644\u0648\u0628.\"\/><span class=\"mailpoet_error_r2gqr\"><\/span><\/div>\n<div class=\"mailpoet_paragraph \"><fieldset><legend class=\"mailpoet_segment_label\" >Liste(n) ausw\u00e4hlen:<\/legend><label class=\"mailpoet_checkbox_label\" for=\"mailpoet_segment_1\" ><input type=\"checkbox\" class=\"mailpoet_checkbox\" id=\"mailpoet_segment_1\" name=\"data[form_field_ZmE2Y2IzYTVjMzI3X3NlZ21lbnRz][]\" value=\"6\"  data-parsley-errors-container=\".mailpoet_error_cmqrf\" data-parsley-required=\"true\" required aria-required=\"true\" data-parsley-group=\"segments\" data-parsley-required-message=\"\u064a\u0631\u062c\u0649 \u062a\u062d\u062f\u064a\u062f \u0642\u0627\u0626\u0645\u0629.\" \/> Presse Verteiler &#8211; Deutsch<\/label><label class=\"mailpoet_checkbox_label\" for=\"mailpoet_segment_2\" ><input type=\"checkbox\" class=\"mailpoet_checkbox\" id=\"mailpoet_segment_2\" name=\"data[form_field_ZmE2Y2IzYTVjMzI3X3NlZ21lbnRz][]\" value=\"7\"  data-parsley-errors-container=\".mailpoet_error_cmqrf\" data-parsley-required=\"true\" required aria-required=\"true\" data-parsley-group=\"segments\" data-parsley-required-message=\"\u064a\u0631\u062c\u0649 \u062a\u062d\u062f\u064a\u062f \u0642\u0627\u0626\u0645\u0629.\" \/> Press Mailing list &#8211; English<\/label><label class=\"mailpoet_checkbox_label\" for=\"mailpoet_segment_3\" ><input type=\"checkbox\" class=\"mailpoet_checkbox\" id=\"mailpoet_segment_3\" name=\"data[form_field_ZmE2Y2IzYTVjMzI3X3NlZ21lbnRz][]\" value=\"8\"  data-parsley-errors-container=\".mailpoet_error_cmqrf\" data-parsley-required=\"true\" required aria-required=\"true\" data-parsley-group=\"segments\" data-parsley-required-message=\"\u064a\u0631\u062c\u0649 \u062a\u062d\u062f\u064a\u062f \u0642\u0627\u0626\u0645\u0629.\" \/> \u0642\u0627\u0626\u0645\u0629 \u0628\u0631\u064a\u062f \u0627\u0644\u0635\u062d\u0627\u0641\u0629<\/label><span class=\"mailpoet_error_cmqrf\"><\/span><\/fieldset><\/div>\n<div class=\"mailpoet_paragraph \"><input type=\"submit\" class=\"mailpoet_submit\" value=\"Abonnieren!\" data-automation-id=\"subscribe-submit-button\" style=\"width:100%;box-sizing:border-box;padding:5px;margin: 0 auto 0 0;border-color:transparent;\" \/><span class=\"mailpoet_form_loading\"><span class=\"mailpoet_bounce1\"><\/span><span class=\"mailpoet_bounce2\"><\/span><span class=\"mailpoet_bounce3\"><\/span><\/span><\/div>\n\n      <div class=\"mailpoet_message\">\n        <p class=\"mailpoet_validate_success\"\n                style=\"display:none;\"\n                >Pr\u00fcfe deinen Posteingang oder Spam-Ordner, um dein Abonnement zu best\u00e4tigen.\n        <\/p>\n        <p class=\"mailpoet_validate_error\"\n                style=\"display:none;\"\n                >        <\/p>\n      <\/div>\n    <\/form>\n\n      <\/div>\n\n  <\/div>\r\n<\/div>\r\n\r\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;&#8221;]<\/p>\r\n<h2 style=\"text-align: right;\">\u0644\u0644\u0627\u0639\u062a\u0645\u0627\u062f \u0627\u0644\u0635\u062d\u0627\u0641\u064a \u0627\u0644\u0631\u062c\u0627\u0621 \u0645\u0644\u0626 \u0627\u0644\u0627\u0633\u062a\u0645\u0627\u0631\u0629 \u0628\u0627\u0644\u0644\u063a\u0629 \u0627\u0644\u0627\u0646\u062c\u0644\u064a\u0632\u064a\u0629<\/h2>\r\n<h2 style=\"text-align: right;\"><a href=\"https:\/\/alfilm.berlin\/ar\/presse\/\">PRESS ACCREDITATION<\/a><\/h2>\r\n<p>&nbsp;<\/p>\r\n<p>&nbsp;<\/p>\r\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p><\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] \u0627\u0644\u0635\u062d\u0627\u0641\u0629 \u00a0 \u0627\u0644\u0645\u0643\u062a\u0628 \u0627\u0644\u0635\u062d\u0641\u064a \u064a\u0631\u062c\u0649 \u0625\u0631\u0633\u0627\u0644 \u0627\u0644\u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0627\u062a \u0627\u0644\u0635\u062d\u0641\u064a\u0629 (\u0644\u0644\u0635\u062d\u0627\u0641\u0629 \u0627\u0644\u0639\u0631\u0628\u064a\u0629) \u0625\u0644\u0649\u0646\u0632\u064a\u0647\u0629 \u0633\u0639\u064a\u062fnazeeha@alfilm.berlin \u064a\u0631\u062c\u0649 \u0625\u0631\u0633\u0627\u0644 \u0627\u0644\u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0627\u062a \u0627\u0644\u0635\u062d\u0641\u064a\u0629 \u0644\u0644\u0635\u062d\u0627\u0641\u0629 \u0627\u0644\u0625\u0646\u062c\u0644\u064a\u0632\u064a\u0629 \u0648\u0627\u0644\u0623\u0644\u0645\u0627\u0646\u064a\u0629&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1282","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/alfilm.berlin\/ar\/wp-json\/wp\/v2\/pages\/1282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alfilm.berlin\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alfilm.berlin\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alfilm.berlin\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alfilm.berlin\/ar\/wp-json\/wp\/v2\/comments?post=1282"}],"version-history":[{"count":16,"href":"https:\/\/alfilm.berlin\/ar\/wp-json\/wp\/v2\/pages\/1282\/revisions"}],"predecessor-version":[{"id":9415,"href":"https:\/\/alfilm.berlin\/ar\/wp-json\/wp\/v2\/pages\/1282\/revisions\/9415"}],"wp:attachment":[{"href":"https:\/\/alfilm.berlin\/ar\/wp-json\/wp\/v2\/media?parent=1282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}